{"id":2803,"date":"2019-07-16T15:00:33","date_gmt":"2019-07-16T13:00:33","guid":{"rendered":"https:\/\/ch2021.ch\/?p=2803"},"modified":"2019-08-27T16:13:39","modified_gmt":"2019-08-27T14:13:39","slug":"herstory-le-donne-scrivono-la-storia","status":"publish","type":"post","link":"https:\/\/ch2021.ch\/it\/herstory-le-donne-scrivono-la-storia\/","title":{"rendered":"HerStory: le donne scrivono la storia"},"content":{"rendered":"<p>Tra i molti malintesi e i miti in relazione alle questioni di genere, c\u2019\u00e8 anche l\u2019opinione diffusa che le donne non abbiano una storia e che, di conseguenza, i modelli femminili scarseggino. \u00c8 ovviamente vero il contrario, ma occorre cercarli, in quanto i libri di storia ragionano effettivamente ancora secondo il principio che gli uomini agiscono, le donne fanno presenza.<\/p>\n<p>Proprio la storia della conquista del suffragio femminile ci regala donne straordinarie ed esemplari per la resistenza e il coraggio dimostrati. Utilizzate questi esempi per motivare \u2013 in internet, con esposizioni in luoghi pubblici o distribuendo opuscoli e volantini \u2013 donne e ragazze ad attivarsi in politica.<\/p>\n<p><strong>Come concretizzare l\u2019idea?<\/strong><\/p>\n<p>Raccontate le incredibili storie di donne (politiche) straordinarie, magari ponendole nel contesto di temi di attualit\u00e0, come lo sciopero delle donne del 2019, affinch\u00e9 tutte\/i si sentano interpellate\/i.<\/p>\n<p>Potete anche chiedere a madri, nonne e amiche di scrivere le loro storie. Moltissime testimonianze attendono ancora di essere raccontate.<\/p>\n<p>Rendetele pubbliche, organizzate una mostra in un centro comunale, redigete una serie di articoli per il giornale locale, attivate un portale in internet, lanciate un\u2019iniziativa sui media sociali, create un\u2019applicazione. In breve, rendete tutti partecipi delle storie di queste donne.<\/p>\n<p><strong>Fonti di ispirazione<\/strong><\/p>\n<ul>\n<li>L\u2019applicazione americana \u00abLessons in Herstory\u00bb utilizza la realt\u00e0 aumentata per riportare alla luce storie dimenticate di donne, partendo direttamente dalle pagine di un libro di storia. Gli utenti scansionano il ritratto di un uomo dal loro manuale didattico e l\u2019applicazione fornisce la storia di una donna importante a esso legata. Maggiori informazioni <a href=\"https:\/\/www.lessonsinherstory.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">qui<\/a>.<\/li>\n<li>La raccolta \u00abStoria della buonanotte per bambine ribelli\u00bb contiene le storie di cento donne straordinarie illustrate da oltre sessanta artiste e artisti di tutto il mondo. Maggiori informazioni <a href=\"http:\/\/www.storiedellabuonanotteperbambineribelli.it\/\" target=\"_blank\" rel=\"noopener noreferrer\">qui<\/a>.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Tra i molti malintesi e i miti in relazione alle questioni di genere, c\u2019\u00e8 anche l\u2019opinione diffusa che le donne non abbiano una storia e che, di conseguenza, i modelli femminili scarseggino. \u00c8 ovviamente vero il contrario, ma occorre cercarli, in quanto i libri di storia ragionano effettivamente ancora secondo il principio che gli uomini [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":2227,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[81],"tags":[],"class_list":["post-2803","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-consigli-per-lazione"],"_links":{"self":[{"href":"https:\/\/ch2021.ch\/it\/wp-json\/wp\/v2\/posts\/2803","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ch2021.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ch2021.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ch2021.ch\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/ch2021.ch\/it\/wp-json\/wp\/v2\/comments?post=2803"}],"version-history":[{"count":3,"href":"https:\/\/ch2021.ch\/it\/wp-json\/wp\/v2\/posts\/2803\/revisions"}],"predecessor-version":[{"id":3062,"href":"https:\/\/ch2021.ch\/it\/wp-json\/wp\/v2\/posts\/2803\/revisions\/3062"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ch2021.ch\/it\/wp-json\/wp\/v2\/media\/2227"}],"wp:attachment":[{"href":"https:\/\/ch2021.ch\/it\/wp-json\/wp\/v2\/media?parent=2803"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ch2021.ch\/it\/wp-json\/wp\/v2\/categories?post=2803"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ch2021.ch\/it\/wp-json\/wp\/v2\/tags?post=2803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}