{"id":5359,"date":"2020-05-01T14:45:21","date_gmt":"2020-05-01T12:45:21","guid":{"rendered":"https:\/\/ch2021.ch\/?p=5359"},"modified":"2020-05-08T09:35:30","modified_gmt":"2020-05-08T07:35:30","slug":"demokratie-denken","status":"publish","type":"post","link":"https:\/\/ch2021.ch\/it\/demokratie-denken\/","title":{"rendered":"Pensare alla democrazia"},"content":{"rendered":"<a href=\"https:\/\/ch2021.ch\/author\/zitak\/\" class=\"wp-user-avatar-link wp-user-avatar-custom\" target=\"_blank\"><\/a>\n<p>Nel 2021 ricorre l&#8217;anniversario della democrazia: da 50 anni, infatti, le donne svizzere hanno gli stessi diritti politici degli svizzeri. Ritengo che questa sia una buona occasione per riflettere sulla democrazia.<\/p>\n<p>Appena penso alla parola &#8220;democrazia&#8221;, il mio orizzonte va oltre la mia singola persona. Io da sola non posso fare una democrazia. Cos\u00ec rivolgo il mio sguardo verso il mondo che mi circonda, osservo chi e cos&#8217;altro c&#8217;\u00e8, insieme a me: questa \u00e8 una prima sfida. Tra le altre cose, significa anche rendersi conto che non sarei in grado di sopravvivere senza gli altri. Il mio indiscutibile bisogno di indipendenza e di autonomia \u00e8 infatti importante e giusto. Ma l&#8217;indipendenza \u00e8 solo una faccia della medaglia. L&#8217;altra \u00e8 la necessit\u00e0 di cooperazione, di accettazione e protezione. A seconda della situazione, concentro i miei sforzi su un lato o sull&#8217;altro della medaglia.<\/p>\n<p>La questione della mia indipendenza e autonomia \u00e8 una cosa che posso determinare con me stessa. Si tratta dei miei piani di vita personali. Affinch\u00e9 il mio bisogno di cooperazione, di accettazione e di protezione si realizzi, ho bisogno di altre persone, anzi di un&#8217;intera societ\u00e0. Perch\u00e9 mi sento sicura e protetta solo quando ho cibo, vestiti, riparo e quando ho accesso a salute, istruzione e cultura. Chi determina quali di questi beni sono prodotti e resi disponibili e a quali condizioni? Chi \u00e8 attivamente coinvolto nella produzione e distribuzione di questi beni? Chi vi ha accesso e come? Questa complessa organizzazione pu\u00f2 essere progettata secondo diversi principi. Il &#8220;pensiero della democrazia&#8221; parte da l\u00ec e suggerisce di negoziare e decidere insieme.<\/p>\n<p>Per il 2021 spero che molti riflettano su com&#8217;era quando gli svizzeri decisero che solo gli uomini avrebbero condotto queste trattative e preso decisioni. Una realt\u00e0 che ho vissuto da ragazza. Ad esempio non riuscivo a spiegarmi che mia madre, che &#8220;mandava avanti&#8221; la nostra famiglia, non potesse infilare la sua busta nell&#8217;urna elettorale la domenica delle votazioni e dovesse aspettare insieme a noi bambini mio padre fuori dalla sala delle votazioni. Questo ti segna. Mi chiedo costantemente quando questi ricordi si affacceranno nuovamente.<\/p>\n<p>Non vedo l&#8217;ora di conoscere tutte le storie su come la partecipazione delle donne svizzere dopo il 7 febbraio 1971 si \u00e8 realizzata e quali effetti ha avuto. A segnarmi tanto \u00e8 stato anche il momento in cui ho ricevuto la busta di voto con il mio nome sopra e l&#8217;invito ad esprimere la mia opinione. La nostra democrazia diretta mi d\u00e0 quattro volte l&#8217;anno l&#8217;opportunit\u00e0 di partecipare al processo decisionale su una vasta gamma di questioni. La nostra societ\u00e0 si basa sul presupposto che gli svizzeri di maggiore et\u00e0 debbano formare il popolo e avere voce in capitolo.<\/p>\n<p>Qui confluiscono diverse realt\u00e0 di vita, visioni del mondo, sfondi e interessi. Non \u00e8 facile conciliare tutto questo e creare una coesione sociale! Dove e come ha avuto successo? Dove e come vedo la necessit\u00e0 di un miglioramento? Tutte queste valutazioni sono importanti e fanno parte di un discorso comune. Questo mantiene la democrazia viva e vivace.<\/p>\n<p>Quando abbiamo iniziato i preparativi per il 2021, ho dovuto spiegare pi\u00f9 e pi\u00f9 volte perch\u00e9 la questione della partecipazione delle persone alla democrazia fosse importante. Molto spesso ho scoperto che tanti danno per scontato che per noi questo sia &#8220;cos\u00ec com&#8217;\u00e8&#8221; e non sia nemmeno messo in discussione.<\/p>\n<p>Il Corona virus ci ha raggiunto anche su questo tema. &#8220;Pensare alla democrazia&#8221; ha acquisito una rilevanza drammatica. Chi avrebbe potuto pensare solo due mesi fa che l&#8217;esercito svizzero sarebbe stato mobilitato, che il Consiglio federale avrebbe emanato ordinanze d&#8217;emergenza e che le nostre frontiere sarebbero state chiuse? La sessione parlamentare \u00e8 stata interrotta ed \u00e8 stata stabilita una nuova sessione in condizioni organizzative completamente nuove. Non \u00e8 chiaro quando si potranno tenere le prossime votazioni ed elezioni, perch\u00e9 la formazione preparatoria dell&#8217;opinione pu\u00f2 avvenire solo in misura molto limitata.<\/p>\n<p>Quindi non possiamo continuare a fare quello a cui siamo abituati. Perch\u00e9 la democrazia funzioni, dobbiamo pensare in modo nuovo e scoprire come vogliamo garantire la partecipazione del popolo. Per poter progettare, molti devono anche esprimersi. Devo essere in grado di percepire quali sono le diverse opinioni, quali argomenti vengono presentati, quali interessi entrano in gioco. Quando adesso penso alle persone di riferimento, noto che sono prevalentemente uomini &#8211; non solo in Svizzera. Fanno eccezione le donne che ricoprono una carica ufficiale: la nostra Presidente Federale, la nostra Ministra della Giustizia, la nostra Ministra della Difesa, la Presidente della Conferenza svizzera dei direttori della pubblica educazione, la Presidente della Conferenza delle Direttrici e dei Direttori della sanit\u00e0, la Presidente del Consiglio Nazionale, la Segretaria di Stato al Seco (ho dimenticato qualcuna?). Nelle altre posizioni ci sono uomini.<\/p>\n<p>Inoltre, sono richiesti specialisti del settore sanitario, assistenziale, economico, culturale, sportivo, logistico e legale. Purtroppo, nella maggior parte dei casi sono gli uomini a presentare le loro posizioni e le loro opinioni. Per me \u00e8 importante che si instauri un vero dialogo. Voglio ascoltare esperte donne e sentire la voce delle donne, dove, in tutta la loro diversit\u00e0, vengono introdotti i temi che sono importanti anche per le donne. Una buona convivenza democratica significa che anche gli uomini lo percepiscono e lo esigono. Questo \u00e8 ci\u00f2 che fa progredire la nostra democrazia.<\/p>\n<p>Sar\u00f2 lieta di ricevere tutti i contributi di donne e uomini che riflettono la nostra vita comunitaria. Questo \u00e8 di grande attualit\u00e0 e coinvolgimento. La nostra democrazia ha ancora molto da fare prima del cinquantesimo anniversario del suffragio femminile, il 7 febbraio 2021: vogliamo costruire un futuro in cui convivere con il Corona virus. Per questo abbiamo bisogno dell&#8217;energia e delle idee di tutti.<\/p>\n<p>Rimanete in salute. E pensate alla democrazia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nel 2021 ricorre l&#8217;anniversario della democrazia: da 50 anni, infatti, le donne svizzere hanno gli stessi diritti politici degli svizzeri. Ritengo che questa sia una buona occasione per riflettere sulla democrazia. Appena penso alla parola &#8220;democrazia&#8221;, il mio orizzonte va oltre la mia singola persona. Io da sola non posso fare una democrazia. Cos\u00ec rivolgo [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":5322,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[170],"tags":[],"class_list":["post-5359","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-3"],"_links":{"self":[{"href":"https:\/\/ch2021.ch\/it\/wp-json\/wp\/v2\/posts\/5359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ch2021.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ch2021.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ch2021.ch\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/ch2021.ch\/it\/wp-json\/wp\/v2\/comments?post=5359"}],"version-history":[{"count":3,"href":"https:\/\/ch2021.ch\/it\/wp-json\/wp\/v2\/posts\/5359\/revisions"}],"predecessor-version":[{"id":5648,"href":"https:\/\/ch2021.ch\/it\/wp-json\/wp\/v2\/posts\/5359\/revisions\/5648"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ch2021.ch\/it\/wp-json\/wp\/v2\/media\/5322"}],"wp:attachment":[{"href":"https:\/\/ch2021.ch\/it\/wp-json\/wp\/v2\/media?parent=5359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ch2021.ch\/it\/wp-json\/wp\/v2\/categories?post=5359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ch2021.ch\/it\/wp-json\/wp\/v2\/tags?post=5359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}